{"id":2742,"date":"2021-01-06T13:41:27","date_gmt":"2021-01-06T12:41:27","guid":{"rendered":"https:\/\/www.virtual-dreams.org\/photoroom\/?p=2742"},"modified":"2021-11-07T17:39:22","modified_gmt":"2021-11-07T16:39:22","slug":"turkey-2011","status":"publish","type":"post","link":"https:\/\/www.virtual-dreams.org\/photoroom\/2021\/01\/06\/turkey-2011\/","title":{"rendered":"Turkey 2011"},"content":{"rendered":"\n<!--more-->\n\n\n\n<p>Trip to the Mediterranean region of Turkey in February 2011<\/p>\n\n\n<style type=\"text\/css\" scoped>.rbs_gallery_6a04d915a8de2Spinner{\r\n\t\t\t\tmargin: 50px auto;\r\n\t\t\t\twidth: 50px;\r\n\t\t\t\theight: 40px;\r\n\t\t\t\ttext-align: center;\r\n\t\t\t\tfont-size: 10px;\r\n\t\t\t}\r\n\t\t\t.rbs_gallery_6a04d915a8de2Spinner > div{\r\n\t\t\t  background-color: #333;\r\n\t\t\t  height: 100%;\r\n\t\t\t  width: 6px;\r\n\t\t\t  display: inline-block;\r\n\t\t\t  -webkit-animation: rbs_gallery_6a04d915a8de2-stretchdelay 1.2s infinite ease-in-out;\r\n\t\t\t  animation: rbs_gallery_6a04d915a8de2-stretchdelay 1.2s infinite ease-in-out;\r\n\t\t\t}\r\n\t\t\t.rbs_gallery_6a04d915a8de2Spinner .rbs_gallery_6a04d915a8de2Rect2 {\r\n\t\t\t  -webkit-animation-delay: -1.1s;\r\n\t\t\t  animation-delay: -1.1s;\r\n\t\t\t}\r\n\t\t\t.rbs_gallery_6a04d915a8de2Spinner .rbs_gallery_6a04d915a8de2Rect3 {\r\n\t\t\t  -webkit-animation-delay: -1.0s;\r\n\t\t\t  animation-delay: -1.0s;\r\n\t\t\t}\r\n\t\t\t.rbs_gallery_6a04d915a8de2Spinner .rbs_gallery_6a04d915a8de2Rect4 {\r\n\t\t\t  -webkit-animation-delay: -0.9s;\r\n\t\t\t  animation-delay: -0.9s;\r\n\t\t\t}\r\n\t\t\t.rbs_gallery_6a04d915a8de2Spinner .rbs_gallery_6a04d915a8de2Rect5 {\r\n\t\t\t  -webkit-animation-delay: -0.8s;\r\n\t\t\t  animation-delay: -0.8s;\r\n\t\t\t}\r\n\t\t\t@-webkit-keyframes rbs_gallery_6a04d915a8de2-stretchdelay {\r\n\t\t\t  0%, 40%, 100% { -webkit-transform: scaleY(0.4) }  \r\n\t\t\t  20% { -webkit-transform: scaleY(1.0) }\r\n\t\t\t}\r\n\t\t\t@keyframes rbs_gallery_6a04d915a8de2-stretchdelay {\r\n\t\t\t  0%, 40%, 100% { \r\n\t\t\t    transform: scaleY(0.4);\r\n\t\t\t    -webkit-transform: scaleY(0.4);\r\n\t\t\t  }  20% { \r\n\t\t\t    transform: scaleY(1.0);\r\n\t\t\t    -webkit-transform: scaleY(1.0);\r\n\t\t\t  }\r\n\t\t\t}\r\n\t\t<\/style><div class=\"robo-gallery-wrap robo-gallery-wrap-id3640 robo-gallery-masonry\" ><div id=\"rbs_gallery_6a04d915a8de2-block-loader\" class=\"rbs_gallery_6a04d915a8de2Spinner\"><div class=\"rbs_gallery_6a04d915a8de2Rect1\"><\/div> <div class=\"rbs_gallery_6a04d915a8de2Rect2\"><\/div> <div class=\"rbs_gallery_6a04d915a8de2Rect3\"><\/div> <div class=\"rbs_gallery_6a04d915a8de2Rect4\"><\/div> <div class=\"rbs_gallery_6a04d915a8de2Rect5\"><\/div><\/div><div id=\"robo_gallery_main_block_rbs_gallery_6a04d915a8de2\" class=\"robogallery-gallery-3640\" style=\"width:100%;  display: none;\"><div id=\"rbs_gallery_6a04d915a8de2\" data-options=\"rbs_gallery_6a04d915a8de2\" style=\"width:100%;\" class=\"robo_gallery  \"><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_001.jpg\"  title=\"Turkey_001\"  data-width=\"600\"  data-height=\"201\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_001.jpg\"  title=\"Turkey_001\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_002.JPG\"  title=\"Turkey_002\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_002.JPG\"  title=\"Turkey_002\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_003.JPG\"  title=\"Turkey_003\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_003.JPG\"  title=\"Turkey_003\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_004-1024x682.jpg\"  title=\"Turkey_004\"  data-width=\"620\"  data-height=\"413\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_004.JPG\"  title=\"Turkey_004\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_006.JPG\"  title=\"Turkey_006\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_006.JPG\"  title=\"Turkey_006\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_007.JPG\"  title=\"Turkey_007\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_007.JPG\"  title=\"Turkey_007\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_008.JPG\"  title=\"Turkey_008\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_008.JPG\"  title=\"Turkey_008\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_009.JPG\"  title=\"Turkey_009\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_009.JPG\"  title=\"Turkey_009\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_010.JPG\"  title=\"Turkey_010\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_010.JPG\"  title=\"Turkey_010\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_011-682x1024.jpg\"  title=\"Turkey_011\"  data-width=\"620\"  data-height=\"931\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_011.JPG\"  title=\"Turkey_011\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_012.JPG\"  title=\"Turkey_012\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_012.JPG\"  title=\"Turkey_012\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_013.JPG\"  title=\"Turkey_013\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_013.JPG\"  title=\"Turkey_013\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_014.JPG\"  title=\"Turkey_014\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_014.JPG\"  title=\"Turkey_014\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_015-682x1024.jpg\"  title=\"Turkey_015\"  data-width=\"620\"  data-height=\"931\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_015.JPG\"  title=\"Turkey_015\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_016.JPG\"  title=\"Turkey_016\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_016.JPG\"  title=\"Turkey_016\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_017.JPG\"  title=\"Turkey_017\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_017.JPG\"  title=\"Turkey_017\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_018.JPG\"  title=\"Turkey_018\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_018.JPG\"  title=\"Turkey_018\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_019.JPG\"  title=\"Turkey_019\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_019.JPG\"  title=\"Turkey_019\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_020-1024x682.jpg\"  title=\"Turkey_020\"  data-width=\"620\"  data-height=\"413\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_020.JPG\"  title=\"Turkey_020\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_021.JPG\"  title=\"Turkey_021\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_021.JPG\"  title=\"Turkey_021\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_022.JPG\"  title=\"Turkey_022\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_022.JPG\"  title=\"Turkey_022\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_023.JPG\"  title=\"Turkey_023\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_023.JPG\"  title=\"Turkey_023\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_024.JPG\"  title=\"Turkey_024\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_024.JPG\"  title=\"Turkey_024\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_025-1024x682.jpg\"  title=\"Turkey_025\"  data-width=\"620\"  data-height=\"413\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_025.JPG\"  title=\"Turkey_025\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_026.JPG\"  title=\"Turkey_026\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_026.JPG\"  title=\"Turkey_026\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_027.JPG\"  title=\"Turkey_027\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_027.JPG\"  title=\"Turkey_027\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_028.JPG\"  title=\"Turkey_028\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_028.JPG\"  title=\"Turkey_028\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_029-1024x682.jpg\"  title=\"Turkey_029\"  data-width=\"620\"  data-height=\"413\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_029.JPG\"  title=\"Turkey_029\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_030.JPG\"  title=\"Turkey_030\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_030.JPG\"  title=\"Turkey_030\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_031.JPG\"  title=\"Turkey_031\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_031.JPG\"  title=\"Turkey_031\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_032.JPG\"  title=\"Turkey_032\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_032.JPG\"  title=\"Turkey_032\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_033.JPG\"  title=\"Turkey_033\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_033.JPG\"  title=\"Turkey_033\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_034.JPG\"  title=\"Turkey_034\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_034.JPG\"  title=\"Turkey_034\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_035-682x1024.jpg\"  title=\"Turkey_035\"  data-width=\"620\"  data-height=\"931\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_035.JPG\"  title=\"Turkey_035\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_036.JPG\"  title=\"Turkey_036\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_036.JPG\"  title=\"Turkey_036\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_037.JPG\"  title=\"Turkey_037\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_037.JPG\"  title=\"Turkey_037\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_038.JPG\"  title=\"Turkey_038\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_038.JPG\"  title=\"Turkey_038\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_039-1024x682.jpg\"  title=\"Turkey_039\"  data-width=\"620\"  data-height=\"413\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_039.JPG\"  title=\"Turkey_039\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_040.JPG\"  title=\"Turkey_040\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_040.JPG\"  title=\"Turkey_040\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_041.JPG\"  title=\"Turkey_041\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_041.JPG\"  title=\"Turkey_041\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_042.JPG\"  title=\"Turkey_042\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_042.JPG\"  title=\"Turkey_042\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_043.JPG\"  title=\"Turkey_043\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_043.JPG\"  title=\"Turkey_043\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_044.JPG\"  title=\"Turkey_044\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_044.JPG\"  title=\"Turkey_044\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_045-1024x682.jpg\"  title=\"Turkey_045\"  data-width=\"620\"  data-height=\"413\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_045.JPG\"  title=\"Turkey_045\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_046.JPG\"  title=\"Turkey_046\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_046.JPG\"  title=\"Turkey_046\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_047.JPG\"  title=\"Turkey_047\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_047.JPG\"  title=\"Turkey_047\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_048.JPG\"  title=\"Turkey_048\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_048.JPG\"  title=\"Turkey_048\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_049-682x1024.jpg\"  title=\"Turkey_049\"  data-width=\"620\"  data-height=\"931\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_049.JPG\"  title=\"Turkey_049\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_050.JPG\"  title=\"Turkey_050\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_050.JPG\"  title=\"Turkey_050\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_051.JPG\"  title=\"Turkey_051\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_051.JPG\"  title=\"Turkey_051\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_052.JPG\"  title=\"Turkey_052\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_052.JPG\"  title=\"Turkey_052\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_053.JPG\"  title=\"Turkey_053\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_053.JPG\"  title=\"Turkey_053\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_054-1024x682.jpg\"  title=\"Turkey_054\"  data-width=\"620\"  data-height=\"413\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_054.JPG\"  title=\"Turkey_054\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_055.JPG\"  title=\"Turkey_055\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_055.JPG\"  title=\"Turkey_055\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_056.JPG\"  title=\"Turkey_056\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_056.JPG\"  title=\"Turkey_056\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_057.jpg\"  title=\"Turkey_057\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_057.jpg\"  title=\"Turkey_057\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_058.JPG\"  title=\"Turkey_058\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_058.JPG\"  title=\"Turkey_058\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_059-682x1024.jpg\"  title=\"Turkey_059\"  data-width=\"620\"  data-height=\"931\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_059.JPG\"  title=\"Turkey_059\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_060.JPG\"  title=\"Turkey_060\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_060.JPG\"  title=\"Turkey_060\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_061.JPG\"  title=\"Turkey_061\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_061.JPG\"  title=\"Turkey_061\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_062.JPG\"  title=\"Turkey_062\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_062.JPG\"  title=\"Turkey_062\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_063-1024x682.jpg\"  title=\"Turkey_063\"  data-width=\"620\"  data-height=\"413\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_063.JPG\"  title=\"Turkey_063\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_064.JPG\"  title=\"Turkey_064\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_064.JPG\"  title=\"Turkey_064\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_065.JPG\"  title=\"Turkey_065\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_065.JPG\"  title=\"Turkey_065\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_066.JPG\"  title=\"Turkey_066\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_066.JPG\"  title=\"Turkey_066\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_067.JPG\"  title=\"Turkey_067\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_067.JPG\"  title=\"Turkey_067\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_068-682x1024.jpg\"  title=\"Turkey_068\"  data-width=\"620\"  data-height=\"931\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_068.JPG\"  title=\"Turkey_068\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_069.JPG\"  title=\"Turkey_069\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_069.JPG\"  title=\"Turkey_069\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_070.JPG\"  title=\"Turkey_070\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_070.JPG\"  title=\"Turkey_070\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_071.JPG\"  title=\"Turkey_071\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_071.JPG\"  title=\"Turkey_071\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_072.JPG\"  title=\"Turkey_072\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_072.JPG\"  title=\"Turkey_072\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_073-682x1024.jpg\"  title=\"Turkey_073\"  data-width=\"620\"  data-height=\"931\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_073.JPG\"  title=\"Turkey_073\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_074.JPG\"  title=\"Turkey_074\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_074.JPG\"  title=\"Turkey_074\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_075.JPG\"  title=\"Turkey_075\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_075.JPG\"  title=\"Turkey_075\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_076.JPG\"  title=\"Turkey_076\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_076.JPG\"  title=\"Turkey_076\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_077-682x1024.jpg\"  title=\"Turkey_077\"  data-width=\"620\"  data-height=\"931\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_077.JPG\"  title=\"Turkey_077\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_078.JPG\"  title=\"Turkey_078\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_078.JPG\"  title=\"Turkey_078\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_079.JPG\"  title=\"Turkey_079\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_079.JPG\"  title=\"Turkey_079\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_080.JPG\"  title=\"Turkey_080\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_080.JPG\"  title=\"Turkey_080\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_081.JPG\"  title=\"Turkey_081\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_081.JPG\"  title=\"Turkey_081\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_082.JPG\"  title=\"Turkey_082\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_082.JPG\"  title=\"Turkey_082\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_083-682x1024.jpg\"  title=\"Turkey_083\"  data-width=\"620\"  data-height=\"931\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_083.JPG\"  title=\"Turkey_083\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_084.JPG\"  title=\"Turkey_084\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_084.JPG\"  title=\"Turkey_084\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_085.JPG\"  title=\"Turkey_085\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_085.JPG\"  title=\"Turkey_085\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_086-682x1024.jpg\"  title=\"Turkey_086\"  data-width=\"620\"  data-height=\"931\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_086.JPG\"  title=\"Turkey_086\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_087.JPG\"  title=\"Turkey_087\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_087.JPG\"  title=\"Turkey_087\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_088.JPG\"  title=\"Turkey_088\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_088.JPG\"  title=\"Turkey_088\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_089.JPG\"  title=\"Turkey_089\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_089.JPG\"  title=\"Turkey_089\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_090.JPG\"  title=\"Turkey_090\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_090.JPG\"  title=\"Turkey_090\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_091.JPG\"  title=\"Turkey_091\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_091.JPG\"  title=\"Turkey_091\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_092.JPG\"  title=\"Turkey_092\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_092.JPG\"  title=\"Turkey_092\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_093-1024x682.jpg\"  title=\"Turkey_093\"  data-width=\"620\"  data-height=\"413\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_093.JPG\"  title=\"Turkey_093\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_094.JPG\"  title=\"Turkey_094\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_094.JPG\"  title=\"Turkey_094\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_095.JPG\"  title=\"Turkey_095\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_095.JPG\"  title=\"Turkey_095\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_096.JPG\"  title=\"Turkey_096\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_096.JPG\"  title=\"Turkey_096\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_097-682x1024.jpg\"  title=\"Turkey_097\"  data-width=\"620\"  data-height=\"931\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_097.JPG\"  title=\"Turkey_097\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_098.JPG\"  title=\"Turkey_098\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_098.JPG\"  title=\"Turkey_098\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_099.JPG\"  title=\"Turkey_099\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_099.JPG\"  title=\"Turkey_099\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_100.JPG\"  title=\"Turkey_100\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_100.JPG\"  title=\"Turkey_100\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_101-682x1024.jpg\"  title=\"Turkey_101\"  data-width=\"620\"  data-height=\"931\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_101.JPG\"  title=\"Turkey_101\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_102.JPG\"  title=\"Turkey_102\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_102.JPG\"  title=\"Turkey_102\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_103.JPG\"  title=\"Turkey_103\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_103.JPG\"  title=\"Turkey_103\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_104.JPG\"  title=\"Turkey_104\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_104.JPG\"  title=\"Turkey_104\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_105.JPG\"  title=\"Turkey_105\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_105.JPG\"  title=\"Turkey_105\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_106.JPG\"  title=\"Turkey_106\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_106.JPG\"  title=\"Turkey_106\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_107-1024x682.jpg\"  title=\"Turkey_107\"  data-width=\"620\"  data-height=\"413\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_107.JPG\"  title=\"Turkey_107\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_108.JPG\"  title=\"Turkey_108\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_108.JPG\"  title=\"Turkey_108\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_109.JPG\"  title=\"Turkey_109\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_109.JPG\"  title=\"Turkey_109\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_110.JPG\"  title=\"Turkey_110\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_110.JPG\"  title=\"Turkey_110\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_111-1024x682.jpg\"  title=\"Turkey_111\"  data-width=\"620\"  data-height=\"413\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_111.JPG\"  title=\"Turkey_111\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_112.JPG\"  title=\"Turkey_112\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_112.JPG\"  title=\"Turkey_112\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_113.JPG\"  title=\"Turkey_113\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_113.JPG\"  title=\"Turkey_113\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_114.JPG\"  title=\"Turkey_114\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_114.JPG\"  title=\"Turkey_114\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_115.JPG\"  title=\"Turkey_115\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_115.JPG\"  title=\"Turkey_115\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_116.JPG\"  title=\"Turkey_116\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_116.JPG\"  title=\"Turkey_116\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_117-682x1024.jpg\"  title=\"Turkey_117\"  data-width=\"620\"  data-height=\"931\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_117.JPG\"  title=\"Turkey_117\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_118.JPG\"  title=\"Turkey_118\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_118.JPG\"  title=\"Turkey_118\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_119.JPG\"  title=\"Turkey_119\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_119.JPG\"  title=\"Turkey_119\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_120.JPG\"  title=\"Turkey_120\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_120.JPG\"  title=\"Turkey_120\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_121-1024x682.jpg\"  title=\"Turkey_121\"  data-width=\"620\"  data-height=\"413\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_121.JPG\"  title=\"Turkey_121\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_122.JPG\"  title=\"Turkey_122\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_122.JPG\"  title=\"Turkey_122\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_123.JPG\"  title=\"Turkey_123\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_123.JPG\"  title=\"Turkey_123\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_124.JPG\"  title=\"Turkey_124\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_124.JPG\"  title=\"Turkey_124\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_125-682x1024.jpg\"  title=\"Turkey_125\"  data-width=\"620\"  data-height=\"931\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_125.JPG\"  title=\"Turkey_125\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_126.JPG\"  title=\"Turkey_126\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_126.JPG\"  title=\"Turkey_126\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_127.JPG\"  title=\"Turkey_127\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_127.JPG\"  title=\"Turkey_127\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_128.JPG\"  title=\"Turkey_128\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_128.JPG\"  title=\"Turkey_128\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_129.JPG\"  title=\"Turkey_129\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_129.JPG\"  title=\"Turkey_129\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_130.JPG\"  title=\"Turkey_130\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_130.JPG\"  title=\"Turkey_130\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_131-1024x682.jpg\"  title=\"Turkey_131\"  data-width=\"620\"  data-height=\"413\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_131.JPG\"  title=\"Turkey_131\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_132.JPG\"  title=\"Turkey_132\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_132.JPG\"  title=\"Turkey_132\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_133.JPG\"  title=\"Turkey_133\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_133.JPG\"  title=\"Turkey_133\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_134-682x1024.jpg\"  title=\"Turkey_134\"  data-width=\"620\"  data-height=\"931\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_134.JPG\"  title=\"Turkey_134\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_135.JPG\"  title=\"Turkey_135\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_135.JPG\"  title=\"Turkey_135\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_136.JPG\"  title=\"Turkey_136\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_136.JPG\"  title=\"Turkey_136\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_137.JPG\"  title=\"Turkey_137\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_137.JPG\"  title=\"Turkey_137\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_138.JPG\"  title=\"Turkey_138\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_138.JPG\"  title=\"Turkey_138\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_139.JPG\"  title=\"Turkey_139\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_139.JPG\"  title=\"Turkey_139\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_140.JPG\"  title=\"Turkey_140\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_140.JPG\"  title=\"Turkey_140\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_141-682x1024.jpg\"  title=\"Turkey_141\"  data-width=\"620\"  data-height=\"931\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_141.JPG\"  title=\"Turkey_141\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_142.JPG\"  title=\"Turkey_142\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_142.JPG\"  title=\"Turkey_142\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_143.JPG\"  title=\"Turkey_143\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_143.JPG\"  title=\"Turkey_143\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_144.JPG\"  title=\"Turkey_144\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_144.JPG\"  title=\"Turkey_144\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_145-1024x682.jpg\"  title=\"Turkey_145\"  data-width=\"620\"  data-height=\"413\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_145.JPG\"  title=\"Turkey_145\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_146.JPG\"  title=\"Turkey_146\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_146.JPG\"  title=\"Turkey_146\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_147.JPG\"  title=\"Turkey_147\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_147.JPG\"  title=\"Turkey_147\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_148.JPG\"  title=\"Turkey_148\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_148.JPG\"  title=\"Turkey_148\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_149-682x1024.jpg\"  title=\"Turkey_149\"  data-width=\"620\"  data-height=\"931\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_149.JPG\"  title=\"Turkey_149\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_150.JPG\"  title=\"Turkey_150\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_150.JPG\"  title=\"Turkey_150\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_151.JPG\"  title=\"Turkey_151\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_151.JPG\"  title=\"Turkey_151\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_152.JPG\"  title=\"Turkey_152\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_152.JPG\"  title=\"Turkey_152\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_153.JPG\"  title=\"Turkey_153\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_153.JPG\"  title=\"Turkey_153\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_154.JPG\"  title=\"Turkey_154\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_154.JPG\"  title=\"Turkey_154\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_155-682x1024.jpg\"  title=\"Turkey_155\"  data-width=\"620\"  data-height=\"931\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_155.JPG\"  title=\"Turkey_155\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_156.JPG\"  title=\"Turkey_156\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_156.JPG\"  title=\"Turkey_156\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_157.JPG\"  title=\"Turkey_157\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_157.JPG\"  title=\"Turkey_157\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_158.JPG\"  title=\"Turkey_158\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_158.JPG\"  title=\"Turkey_158\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_159-682x1024.jpg\"  title=\"Turkey_159\"  data-width=\"620\"  data-height=\"931\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_159.JPG\"  title=\"Turkey_159\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_160.JPG\"  title=\"Turkey_160\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_160.JPG\"  title=\"Turkey_160\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_161.JPG\"  title=\"Turkey_161\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_161.JPG\"  title=\"Turkey_161\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_162.JPG\"  title=\"Turkey_162\"  data-width=\"600\"  data-height=\"399\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_162.JPG\"  title=\"Turkey_162\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_163.JPG\"  title=\"Turkey_163\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_163.JPG\"  title=\"Turkey_163\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_164-682x1024.jpg\"  title=\"Turkey_164\"  data-width=\"620\"  data-height=\"931\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_164.JPG\"  title=\"Turkey_164\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><div class=\"rbs-img  category3640 \" ><div class=\"rbs-img-image   rbs-lightbox \" ><div class=\"rbs-img-thumbs\"  data-thumbnail=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_165.JPG\"  title=\"Turkey_165\"  data-width=\"600\"  data-height=\"901\" ><\/div><div class=\"rbs-img-data-popup\"  data-popup=\"https:\/\/www.virtual-dreams.org\/photoroom\/wp-content\/uploads\/Turkey-2011\/Turkey_165.JPG\"  title=\"Turkey_165\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsIcons\"><i class=\"fa fa-plus rbsZoomIcon \" ><\/i><\/div><\/div><\/div><\/div><\/div><\/div><\/div><script>var rbs_gallery_6a04d915a8de2 = {\"version\":\"3.2.21\",\"id\":3640,\"class\":\"id3640\",\"roboGalleryDelay\":1000,\"mainContainer\":\"#robo_gallery_main_block_rbs_gallery_6a04d915a8de2\",\"loadingContainer\":\"#rbs_gallery_6a04d915a8de2-block-loader\",\"loadingContainerObj\":\"rbs_gallery_6a04d915a8de2-block-loader\",\"columnWidth\":\"auto\",\"columns\":3,\"resolutions\":[{\"columnWidth\":\"auto\",\"columns\":3,\"maxWidth\":960},{\"columnWidth\":\"auto\",\"columns\":2,\"maxWidth\":650},{\"columnWidth\":\"auto\",\"columns\":1,\"maxWidth\":450}],\"lightboxOptions\":{\"gallery\":{\"enabled\":true,\"tCounter\":\"%curr% of %total%\"}},\"overlayEffect\":\"direction-aware-fade\",\"boxesToLoadStart\":16,\"boxesToLoad\":8,\"waitUntilThumbLoads\":1,\"LoadingWord\":\"Loading...\",\"loadMoreWord\":\"Load More\",\"noMoreEntriesWord\":\"No More Entries\",\"horizontalSpaceBetweenBoxes\":15,\"verticalSpaceBetweenBoxes\":15,\"lazyLoad\":1,\"wrapContainer\":\"#robo-gallery-wrap-rbs_gallery_6a04d915a8de2\"};<\/script>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":2719,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"yes","footnotes":""},"categories":[6,5,4],"tags":[12,38,44,37],"class_list":["post-2742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europe","category-landscape","category-travels","tag-europe","tag-mediterranean","tag-travels","tag-turkey"],"_links":{"self":[{"href":"https:\/\/www.virtual-dreams.org\/photoroom\/wp-json\/wp\/v2\/posts\/2742"}],"collection":[{"href":"https:\/\/www.virtual-dreams.org\/photoroom\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.virtual-dreams.org\/photoroom\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.virtual-dreams.org\/photoroom\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virtual-dreams.org\/photoroom\/wp-json\/wp\/v2\/comments?post=2742"}],"version-history":[{"count":2,"href":"https:\/\/www.virtual-dreams.org\/photoroom\/wp-json\/wp\/v2\/posts\/2742\/revisions"}],"predecessor-version":[{"id":3642,"href":"https:\/\/www.virtual-dreams.org\/photoroom\/wp-json\/wp\/v2\/posts\/2742\/revisions\/3642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.virtual-dreams.org\/photoroom\/wp-json\/wp\/v2\/media\/2719"}],"wp:attachment":[{"href":"https:\/\/www.virtual-dreams.org\/photoroom\/wp-json\/wp\/v2\/media?parent=2742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.virtual-dreams.org\/photoroom\/wp-json\/wp\/v2\/categories?post=2742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.virtual-dreams.org\/photoroom\/wp-json\/wp\/v2\/tags?post=2742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}